{"id":54031,"date":"2025-11-05T12:52:30","date_gmt":"2025-11-05T12:52:30","guid":{"rendered":"https:\/\/jm-graphics.com\/?post_type=product&#038;p=54031"},"modified":"2025-11-05T12:57:26","modified_gmt":"2025-11-05T12:57:26","slug":"riskless-adapted-ktm-scarp-carbon-2020","status":"publish","type":"product","link":"https:\/\/jm-graphics.com\/pt-pt\/produto\/riskless-adapted-ktm-scarp-carbon-2020\/","title":{"rendered":"RISKLESS Adapted \u2013 KTM Scarp Carbon 2020"},"content":{"rendered":"\n<p>A origem RISKLESS, onde tudo come\u00e7a, a prote\u00e7\u00e3o que n\u00e3o pode faltar a nenhum aficionado de bicicletas. Este kit consegue n\u00e3o s\u00f3 proteger desloca\u00e7\u00f5es citadinas, estrada e btt, como vai mais al\u00e9m garantindo a prote\u00e7\u00e3o das partes mais importante da sua bicicleta em terrenos mais t\u00e9cnicos.<\/p>\n<p>RISKLESS Premium n\u00e3o apenas define o padr\u00e3o, mas eleva-se majestosamente como o pin\u00e1culo supremo da evolu\u00e7\u00e3o em materiais de prote\u00e7\u00e3o dispon\u00edveis no mercado. Assim ter\u00e1 a prote\u00e7\u00e3o da sua bicicleta sempre no seu melhor estado com as caracter\u00edsticas auto regenerativas e de UV est\u00e1vel.<\/p>\n<p>Este material, por ser premium, encontra-se dispon\u00edvel em brilho e matte.<\/p>\n<h2><strong>CARACTER\u00cdSTICAS:<\/strong><\/h2>\n<p><strong>EXTREMAMENTE RESISTENTE | <\/strong>Feito em Poliuretano com 200micron de espessura, este ir\u00e1 proteger a tua bicicleta de grande parte dos riscos e impactos que a mesma tende a sofrer.<\/p>\n<p><strong>AUTO-REGENERATIVO | <\/strong>A maioria das pel\u00edculas tendem a ficar riscada com o uso. RISKLESS PREMIUM N\u00c3O! RISKLESS PREMIUM auto regenera-se com o tempo ou com a ajuda de calor, fazendo com que as pequenas marcas e riscos desapare\u00e7am, mantendo sempre o aspeto novo!<\/p>\n<p><strong>TRANSPAR\u00caNCIA | <\/strong>Sabemos o quanto gosta da sua bicicleta. Com a transpar\u00eancia das nossas pel\u00edculas, a beleza da sua bicicleta n\u00e3o ser\u00e1 afetada.<\/p>\n<p><strong>ELASTICIDADE | <\/strong>O material Standard \u00e9 bastante male\u00e1vel, pelo que a sua adapta\u00e7\u00e3o \u00e0s irregularidades das superf\u00edcies n\u00e3o ser\u00e1 um problema.<\/p>\n<p><strong>UV EST\u00c1VEL | <\/strong>RISKLESS PREMIUM n\u00e3o se deixa afetar pela radia\u00e7\u00e3o UV. N\u00e3o amarela, n\u00e3o racha, nem deixa manchas no seu quadro quando removido, principalmente em cores claras, vivas ou fluorescentes!<\/p>\n<p><strong>BRILHO VS FOSCO | <\/strong>Sendo material premium o cliente tem op\u00e7\u00e3o de escolher se pretende o mesmo em brilho, refletindo a sensa\u00e7\u00e3o de polidez e brilho ou ent\u00e3o em matte, um material mais suave, com cores menos saturadas devido \u00e0 difus\u00e3o da luz minimizando reflexos e brilhos.<\/p>\n<p><strong>F\u00c1CIL DE APLICAR | <\/strong>Com a ajuda de \u00e1gua, poder\u00e1 alcan\u00e7ar um resultado final perfeito, tal como um profissional. Veja o nosso v\u00eddeo de    <a style=\"color: #00a0e3;\" href=\"https:\/\/www.youtube.com\/watch?v=MzMDR5GQa7Y\" target=\"_blank\" rel=\"noopener\"><strong>Como aplicar pel\u00edculas de prote\u00e7\u00e3o RISKLESS Premium<\/strong><\/a><\/p>\n<h2><strong>ESPECIFICA\u00c7\u00d5ES T\u00c9CNICAS:<\/strong><\/h2>\n<ul>\n<li><strong>MATERIAL | <\/strong>PU<\/li>\n<li><strong>ESPESSURA | <\/strong>200 microns<\/li>\n<li><strong>ADESIVO | <\/strong>Copol\u00edmero Acr\u00edlico<\/li>\n<li><strong>RESIST\u00caNCIA \u00c0 TEMPERATURA | <\/strong>-30\u00b0C a 110\u00b0C<\/li>\n<li><strong>DURABILIDADE EXPECT\u00c1VEL | <\/strong>At\u00e9 8 anos<\/li>\n<\/ul>\n<p>    <!-- End of content --><\/p>\n\n","protected":false},"excerpt":{"rendered":"A origem RISKLESS, onde tudo come\u00e7a, a prote\u00e7\u00e3o que n\u00e3o pode faltar a nenhum aficionado de bicicletas. Este kit consegue n\u00e3o s\u00f3 proteger desloca\u00e7\u00f5es citadinas, estrada e btt, como vai mais al\u00e9m garantindo a prote\u00e7\u00e3o das partes mais importante da sua bicicleta em terrenos mais t\u00e9cnicos. RISKLESS Premium n\u00e3o apenas define o padr\u00e3o, mas eleva-se...","protected":false},"featured_media":54035,"template":"","meta":[],"product_brand":[],"product_cat":[3204,255,519,2695],"product_tag":[2024,2697,1294,2368,1434,935,2702,1431,1435,1430,2791,1432,2703],"class_list":{"0":"post-54031","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-rl-ktm-fr-pt-pt","7":"product_cat-protecao","8":"product_cat-p-frame-pt-pt","9":"product_cat-rl-adap-pt-pt","10":"product_tag-2020-pt-pt","11":"product_tag-adapted-pt-pt","12":"product_tag-advanced-pt-pt","13":"product_tag-autoregenerativo","14":"product_tag-bike-pt-pt","15":"product_tag-carbon-pt-pt","16":"product_tag-ktm-pt-pt","17":"product_tag-peliculas","18":"product_tag-premium-pt-pt","19":"product_tag-protecao","20":"product_tag-frame-pt-pt","21":"product_tag-riskless-pt-pt","22":"product_tag-scarp-pt-pt","23":"product_shipping_class-caixa-tubular-l","24":"wcpa_has_options","26":"first","27":"instock","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-variable"},"aioseo_notices":[],"wcpa_form_fields":{"wcpaData":{"product":{"product_price":80,"price_html":"<span class=\"woocommerce-Price-amount amount\"><bdi>80,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span>","original_product_price":80,"price_including_tax":80,"price_excluding_tax":65.04065,"product_id":{"parent":54031,"variation":false},"is_variable":true,"stock_status":"instock","stock_quantity":null,"parent_sku":"RL-AD-FRP-22","product_attributes":{"pa_frame-size":{"is_variation":true,"values":[]}},"custom_fields":[],"is_taxable":true,"product_name":"RISKLESS Adapted \u2013 KTM Scarp Carbon 2020","hasImage":false},"fields":{"sec_36765da3c73ea7":{"extra":{"key":"sec_36765da3c73ea7","section_id":"sec_36765da3c73ea7","name":"Default","status":1,"cl_rule":"show","enableCl":false,"relations":[],"toggle":true,"title_tag":"h3","show_title":false,"showPrice":"default","form_id":45668,"form_rules":{"exclude_from_discount":false,"fee_label":"Fee","disp_hide_options_price":true,"disp_show_section_price":false,"disp_show_field_price":false,"layout_option":"standard","pric_use_as_fee":false,"process_fee_as":"woo_fee"},"layout_option":"standard"},"fields":[[{"active":true,"col":6,"relations":false,"cl_rule":"show","enableCl":false,"price":"","enablePrice":false,"className":"","label_position":"default","desc_position":"default","type":"header","required":false,"elementId":"header_3059549677","label":"ADAPTED Series","subtype":"h2","error":false,"enableDesign":true,"LabelColor":"#009ee3","gt_translate_keys":["label"],"price_dependency":false,"cl_dependency":false,"value":""}],[{"active":true,"col":6,"relations":false,"cl_rule":"show","enableCl":false,"price":"","enablePrice":false,"className":"","label_position":"default","desc_position":"default","type":"content","required":false,"elementId":"content_2987879107","label":"","name":"content_2987879107","contentType":"rich","value":"<p>Feito \u00e0 medida para o seu quadro, o RISKLESS Adapted Frame Protector oferece pe\u00e7as maiores que um kit universal e com uma cobertura at\u00e9 60%. Adaptada ao seu modelo, tamanho e ano, garante precis\u00e3o e durabilidade.&nbsp;<\/p>","error":false,"gt_translate_keys":["label","value"],"price_dependency":false,"cl_dependency":false}],[{"active":true,"col":6,"relations":false,"cl_rule":"show","enableCl":false,"price":"","enablePrice":false,"className":"","label_position":"default","desc_position":"default","type":"header","required":false,"elementId":"header_1500541014","label":"Acabamento da Pel\u00edcula de Prote\u00e7\u00e3o","subtype":"h2","error":false,"enableDesign":true,"LabelColor":"#009ee3","gt_translate_keys":["label"],"price_dependency":false,"cl_dependency":false,"value":""}],[{"active":true,"col":6,"relations":false,"cl_rule":"show","enableCl":false,"price":"","enablePrice":false,"className":"","label_position":"default","desc_position":"default","type":"content","required":false,"elementId":"content_7358611267","label":"","name":"content_7358611267","contentType":"rich","value":"<p>Recomendamos escolher o acabamento que corresponda \u00e0 pintura do seu quadro, para garantir que as pel\u00edculas de prote\u00e7\u00e3o permane\u00e7am o mais discretas poss\u00edvel,<\/p>","error":false,"gt_translate_keys":["label","value"],"price_dependency":false,"cl_dependency":false}],[{"active":true,"col":6,"relations":false,"cl_rule":"show","enableCl":false,"price":"","enablePrice":false,"className":"","label_position":"default","desc_position":"default","type":"radio-group","required":true,"elementId":"radio_1543768676","label":"Tipo de Pel\u00edcula","name":"radio_1543768676","values":[{"label":"Premium Brilho","value":"gloss","selected":false,"tempId":"aco_782","gt_translate_keys":["label"]},{"label":"Premium Fosco","value":"matte","selected":false,"tempId":"aco_783","gt_translate_keys":["label"]}],"layOut":"inline","error":false,"checkUi":"","tooltip":"Visite esta <b><a href=\"https:\/\/jm-graphics.com\/pt-pt\/perguntas-frequentes\/tipos-de-acabamentos\/\" target=\"_blank\">P\u00c1GINA<\/a><\/b> se tiver alguma d\u00favida sobre a sua escolha.","gt_translate_keys":["label","tooltip"],"price_dependency":false,"cl_dependency":false,"value":""}]]}},"config":{"price_override":"","enable_recaptcha":false,"bind_quantity":false,"quantity_bind_formula":false,"disp_summ_show_option_price":true,"disp_summ_show_product_price":true,"disp_summ_show_total_price":true,"disp_summ_show_fee":false,"disp_summ_show_discount":false,"summary_title":"","options_total_label":"Options Price","total_label":"Total","options_product_label":"Product Price","fee_label":"Fee","discount_label":"Discount","has_price":true,"has_quantity_formula":false},"mc_unit":1,"tax_rate":1,"tax_rate_real":0.23,"discount":{"percentage":0,"fixed":0},"design":{"conf":{"LabelPosition":"above","DescPosition":"above","UploadField":"custom_1","QuantityFieldStyle":"custom_1"},"css":{"LeftLabelWidth":"120px"}},"formulas":[],"lookuptables":[],"clones":false,"cartKey":false}},"_links":{"self":[{"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/product\/54031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/media\/54035"}],"wp:attachment":[{"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=54031"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=54031"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=54031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jm-graphics.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=54031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}